{"id":768,"date":"2026-08-14T00:14:18","date_gmt":"2026-08-14T00:14:18","guid":{"rendered":"https:\/\/asjfnews.org\/member\/abdul-latif-adil\/"},"modified":"2026-08-14T00:14:18","modified_gmt":"2026-08-14T00:14:18","slug":"abdul-latif-adil","status":"publish","type":"member","link":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/","title":{"rendered":"Abdul Latif Adil"},"content":{"rendered":"<p>Sukon News<\/p>\n<p>abdullatifadil67@gmail.com<\/p>\n<p>700833936<\/p>\n<p>ASJF-26.102<\/p>\n<p>Abdul Latif Adil.jpg<\/p>","protected":false},"featured_media":0,"template":"","class_list":["post-768","member","type-member","status-publish","hentry"],"acf":{"name":"","media_organization":"","contact_email":"","whatsapp__mobile":"","member_id":"","member_photo":null},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Afghanistan Sport Journalists Federation -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Abdul Latif Adil - Afghanistan Sport Journalists Federation\" \/>\n\t\t<meta property=\"og:description\" content=\"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-08-14T00:14:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-14T00:14:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Abdul Latif Adil - Afghanistan Sport Journalists Federation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/asjfnews.org\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/#listItem\",\"name\":\"Members\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/#listItem\",\"position\":2,\"name\":\"Members\",\"item\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#listItem\",\"name\":\"Abdul Latif Adil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#listItem\",\"position\":3,\"name\":\"Abdul Latif Adil\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/#listItem\",\"name\":\"Members\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/#organization\",\"name\":\"Afghanistan Sport Journalists Federation\",\"url\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asjfnews.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/2-scaled.png\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#organizationLogo\",\"width\":2560,\"height\":1175},\"image\":{\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#webpage\",\"url\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/\",\"name\":\"Abdul Latif Adil - Afghanistan Sport Journalists Federation\",\"description\":\"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/member\\\/abdul-latif-adil\\\/#breadcrumblist\"},\"datePublished\":\"2026-08-14T00:14:18+00:00\",\"dateModified\":\"2026-08-14T00:14:18+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/\",\"name\":\"Afghanistan Sport Journalists Federation\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/asjfnews.org\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Abdul Latif Adil - Afghanistan Sport Journalists Federation","description":"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg","canonical_url":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de#listItem","position":1,"name":"Home","item":"https:\/\/asjfnews.org\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de\/member\/#listItem","name":"Members"}},{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de\/member\/#listItem","position":2,"name":"Members","item":"https:\/\/asjfnews.org\/de\/member\/","nextItem":{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#listItem","name":"Abdul Latif Adil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#listItem","position":3,"name":"Abdul Latif Adil","previousItem":{"@type":"ListItem","@id":"https:\/\/asjfnews.org\/de\/member\/#listItem","name":"Members"}}]},{"@type":"Organization","@id":"https:\/\/asjfnews.org\/de\/#organization","name":"Afghanistan Sport Journalists Federation","url":"https:\/\/asjfnews.org\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png","@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#organizationLogo","width":2560,"height":1175},"image":{"@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#webpage","url":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/","name":"Abdul Latif Adil - Afghanistan Sport Journalists Federation","description":"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/asjfnews.org\/de\/#website"},"breadcrumb":{"@id":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/#breadcrumblist"},"datePublished":"2026-08-14T00:14:18+00:00","dateModified":"2026-08-14T00:14:18+00:00"},{"@type":"WebSite","@id":"https:\/\/asjfnews.org\/de\/#website","url":"https:\/\/asjfnews.org\/de\/","name":"Afghanistan Sport Journalists Federation","inLanguage":"de-DE","publisher":{"@id":"https:\/\/asjfnews.org\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Afghanistan Sport Journalists Federation -","og:type":"article","og:title":"Abdul Latif Adil - Afghanistan Sport Journalists Federation","og:description":"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg","og:url":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/","og:image":"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png","og:image:secure_url":"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png","article:published_time":"2026-08-14T00:14:18+00:00","article:modified_time":"2026-08-14T00:14:18+00:00","twitter:card":"summary_large_image","twitter:title":"Abdul Latif Adil - Afghanistan Sport Journalists Federation","twitter:description":"Sukon News abdullatifadil67@gmail.com 700833936 ASJF-26.102 Abdul Latif Adil.jpg","twitter:image":"https:\/\/asjfnews.org\/wp-content\/uploads\/2026\/07\/2-scaled.png"},"aioseo_meta_data":{"post_id":"768","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-08-14 00:46:28","updated":"2026-08-14 00:46:28","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/asjfnews.org\/de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/asjfnews.org\/de\/member\/\" title=\"Members\">Members<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbdul Latif Adil\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/asjfnews.org\/de"},{"label":"Members","link":"https:\/\/asjfnews.org\/de\/member\/"},{"label":"Abdul Latif Adil","link":"https:\/\/asjfnews.org\/de\/member\/abdul-latif-adil\/"}],"_links":{"self":[{"href":"https:\/\/asjfnews.org\/de\/wp-json\/wp\/v2\/member\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asjfnews.org\/de\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/asjfnews.org\/de\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/asjfnews.org\/de\/wp-json\/wp\/v2\/media?parent=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}